{"id":4298,"date":"2021-09-14T14:42:20","date_gmt":"2021-09-14T13:42:20","guid":{"rendered":"https:\/\/www.fyffes.com\/es\/?p=4298"},"modified":"2021-09-14T15:18:47","modified_gmt":"2021-09-14T14:18:47","slug":"finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance","status":"publish","type":"post","link":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/","title":{"rendered":"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance"},"content":{"rendered":"<ul>\n<li><strong>Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma.<\/strong><\/li>\n<li><strong>Certificaci\u00f3n se enfoca en mitigar riesgos ambientales, laborales, sociales y econ\u00f3micos.<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Esmeralda, finca productora de banano de la compa\u00f1\u00eda Fyffes en Costa Rica, es la primera del mundo en recibir la nueva certificaci\u00f3n de Rainforest Alliance, versi\u00f3n 2020, que despliega un enfoque de gesti\u00f3n con cambios radicales hacia los riesgos ambientales, laborales, sociales y econ\u00f3micos.<\/p>\n<p>&nbsp;<\/p>\n<p>Basado en a\u00f1os de exitosa colaboraci\u00f3n, Rainforest Alliance eligi\u00f3 a Fyffes para el lanzamiento en campo de su nueva certificaci\u00f3n. En \u00e9sta se presentan nuevos conceptos tales como un programa de igualdad de g\u00e9nero a nivel de los trabajadores y la implementaci\u00f3n de una herramienta de matriz salarial (resultante de un proyecto conjunto anterior). Tambi\u00e9n se introduce un mecanismo m\u00e1s amplio de evaluaci\u00f3n de riesgos laborales, dando lugar a un plan de gesti\u00f3n integral de operaciones y un enfoque empresarial m\u00e1s claro hacia la sostenibilidad, entre otros objetivos.<\/p>\n<p>&nbsp;<\/p>\n<p>Seg\u00fan indic\u00f3 Jakeline Rodr\u00edguez, Asociada Senior (Sector Frutas) de Rainforest Alliance, eligieron trabajar con Fyffes por su trayectoria positiva con el uso de la norma Rainforest Alliance y por su exitosa asociaci\u00f3n en proyectos anteriores, como el proyecto de Salario Vital en Belice.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cCon este nuevo hito, Fyffes reafirma su estrategia de liderazgo global relacionado con la sostenibilidad. Nuestro compromiso de facilitar el desarrollo de soluciones progresivas, pragm\u00e1ticas e innovadoras junto con los est\u00e1ndares de sostenibilidad se demuestra una vez m\u00e1s, y ayuda a fortalecer la confianza demandada por nuestros clientes\u201d, se\u00f1ala Hugo Hays, Director Global de Seguridad Alimentaria e Inocuidad de Fyffes.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Nueva certificaci\u00f3n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>El nuevo est\u00e1ndar de certificaci\u00f3n de Rainforest Alliance requiere el desarrollo de un sistema de manejo que se centre en la mitigaci\u00f3n y eliminaci\u00f3n de riesgos, por lo que requiere la implementaci\u00f3n de acciones preventivas y correctivas. Tambi\u00e9n requiere la estandarizaci\u00f3n del sistema de gesti\u00f3n en todas las fincas en base a procedimientos y controles establecidos, y un plan de gesti\u00f3n integral en el que se consideren todas las actividades en torno a la operaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s, el nuevo est\u00e1ndar promueve la prevenci\u00f3n y eliminaci\u00f3n de las violaciones de los derechos humanos y el cumplimiento de la legislaci\u00f3n nacional. Como ejemplo, ahora introduce la cuesti\u00f3n de la igualdad de g\u00e9nero a todos los trabajadores de las fincas y empleados y el desarrollo de un mecanismo m\u00e1s amplio de evaluaci\u00f3n de riesgos laborales.<\/p>\n<p>&nbsp;<\/p>\n<p>Entre sus aspectos positivos, el nuevo est\u00e1ndar tambi\u00e9n contribuye a crear una diferenciaci\u00f3n en la comercializaci\u00f3n del producto, ya que requiere acuerdos de responsabilidad compartida entre la finca y los compradores que cumplan con los nuevos requisitos del Diferencial de Sustentabilidad y de Inversiones en Sostenibilidad de Rainforest Alliance.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Fin.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>***<\/p>\n<h3><strong>Sobre Fyffes<\/strong><\/h3>\n<p>Durante m\u00e1s de 130 a\u00f1os, Fyffes ha brindado una selecci\u00f3n de productos tropicales a millones de personas en todo el mundo. Fortalecemos las relaciones con nuestros productores, apoyamos a nuestros empleados y atendemos con diligencia cada eslab\u00f3n de la cadena: la producci\u00f3n, la obtenci\u00f3n, el env\u00edo, la maduraci\u00f3n, la distribuci\u00f3n y la comercializaci\u00f3n, con el objetivo de conseguir la m\u00e1xima calidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Este enfoque le ha valido a Fyffes el liderazgo en varios mercados: somos el mayor importador de banano con certificaci\u00f3n Fairtrade en el mundo, uno de los principales importadores de banano y de pi\u00f1a en Europa y el mayor importador de melones en Norteam\u00e9rica. Nos incorporamos a Sumitomo Corporation en 2017, lo que hizo que nuestro liderazgo en la industria progrese de muchas maneras interesantes.<\/p>\n<p>(<a href=\"http:\/\/www.fyffes.com\/\">www.fyffes.com<\/a>)<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h3><strong>Informaci\u00f3n de contacto<\/strong><\/h3>\n<p>Laura Valverde<\/p>\n<p>lvalverde@cacporternovelli.com<\/p>\n<p>Porter Novelli<\/p>\n<p>8718-4634<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar riesgos ambientales, laborales, sociales y econ\u00f3micos. &nbsp; Esmeralda, finca productora de banano de la compa\u00f1\u00eda Fyffes en Costa Rica, es la primera del mundo en recibir la nueva certificaci\u00f3n de Rainforest [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4302,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[35],"tags":[],"class_list":["post-4298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-comunidad"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance - Fyffes - ES<\/title>\n<meta name=\"description\" content=\"Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance - Fyffes - ES\" \/>\n<meta property=\"og:description\" content=\"Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/\" \/>\n<meta property=\"og:site_name\" content=\"Fyffes - ES\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-14T13:42:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-14T14:18:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fyffes.com\/es\/wp-content\/uploads\/sites\/3\/2021\/09\/Esmeralda-Rainforest-Alliance-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"990\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"sampower\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"sampower\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/\"},\"author\":{\"name\":\"sampower\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/#\\\/schema\\\/person\\\/1f808945ce4f6506661c84191713175b\"},\"headline\":\"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance\",\"datePublished\":\"2021-09-14T13:42:20+00:00\",\"dateModified\":\"2021-09-14T14:18:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/\"},\"wordCount\":683,\"image\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/09\\\/Esmeralda-Rainforest-Alliance-1.png\",\"articleSection\":[\"comunidad\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/\",\"url\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/\",\"name\":\"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance - Fyffes - ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/09\\\/Esmeralda-Rainforest-Alliance-1.png\",\"datePublished\":\"2021-09-14T13:42:20+00:00\",\"dateModified\":\"2021-09-14T14:18:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/#\\\/schema\\\/person\\\/1f808945ce4f6506661c84191713175b\"},\"description\":\"Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/09\\\/Esmeralda-Rainforest-Alliance-1.png\",\"contentUrl\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/09\\\/Esmeralda-Rainforest-Alliance-1.png\",\"width\":2000,\"height\":990},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/\",\"name\":\"Fyffes - ES\",\"description\":\"Our Future is Sustainable\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/#\\\/schema\\\/person\\\/1f808945ce4f6506661c84191713175b\",\"name\":\"sampower\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/436be0e66150be7058de9d0442e56ca570b7d2fced5b180e61e3b72387b4735b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/436be0e66150be7058de9d0442e56ca570b7d2fced5b180e61e3b72387b4735b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/436be0e66150be7058de9d0442e56ca570b7d2fced5b180e61e3b72387b4735b?s=96&d=mm&r=g\",\"caption\":\"sampower\"},\"url\":\"https:\\\/\\\/www.fyffes.com\\\/es\\\/news\\\/author\\\/sampower\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance - Fyffes - ES","description":"Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/","og_locale":"es_ES","og_type":"article","og_title":"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance - Fyffes - ES","og_description":"Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar","og_url":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/","og_site_name":"Fyffes - ES","article_published_time":"2021-09-14T13:42:20+00:00","article_modified_time":"2021-09-14T14:18:47+00:00","og_image":[{"width":2000,"height":990,"url":"https:\/\/www.fyffes.com\/es\/wp-content\/uploads\/sites\/3\/2021\/09\/Esmeralda-Rainforest-Alliance-1.png","type":"image\/png"}],"author":"sampower","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"sampower","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#article","isPartOf":{"@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/"},"author":{"name":"sampower","@id":"https:\/\/www.fyffes.com\/es\/#\/schema\/person\/1f808945ce4f6506661c84191713175b"},"headline":"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance","datePublished":"2021-09-14T13:42:20+00:00","dateModified":"2021-09-14T14:18:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/"},"wordCount":683,"image":{"@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fyffes.com\/es\/wp-content\/uploads\/sites\/3\/2021\/09\/Esmeralda-Rainforest-Alliance-1.png","articleSection":["comunidad"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/","url":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/","name":"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance - Fyffes - ES","isPartOf":{"@id":"https:\/\/www.fyffes.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#primaryimage"},"image":{"@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fyffes.com\/es\/wp-content\/uploads\/sites\/3\/2021\/09\/Esmeralda-Rainforest-Alliance-1.png","datePublished":"2021-09-14T13:42:20+00:00","dateModified":"2021-09-14T14:18:47+00:00","author":{"@id":"https:\/\/www.fyffes.com\/es\/#\/schema\/person\/1f808945ce4f6506661c84191713175b"},"description":"Finca Esmeralda, de la compa\u00f1\u00eda Fyffes, fue elegida para ser parte de programa piloto para implementaci\u00f3n de la norma. Certificaci\u00f3n se enfoca en mitigar","breadcrumb":{"@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#primaryimage","url":"https:\/\/www.fyffes.com\/es\/wp-content\/uploads\/sites\/3\/2021\/09\/Esmeralda-Rainforest-Alliance-1.png","contentUrl":"https:\/\/www.fyffes.com\/es\/wp-content\/uploads\/sites\/3\/2021\/09\/Esmeralda-Rainforest-Alliance-1.png","width":2000,"height":990},{"@type":"BreadcrumbList","@id":"https:\/\/www.fyffes.com\/es\/news\/finca-bananera-en-costa-rica-es-la-primera-en-el-mundo-en-recibir-la-nueva-certificacion-de-rainforest-alliance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.fyffes.com\/es\/"},{"@type":"ListItem","position":2,"name":"Finca Bananera En Costa Rica Es La Primera En El Mundo En Recibir La Nueva Certificaci\u00f3n De Rainforest Alliance"}]},{"@type":"WebSite","@id":"https:\/\/www.fyffes.com\/es\/#website","url":"https:\/\/www.fyffes.com\/es\/","name":"Fyffes - ES","description":"Our Future is Sustainable","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fyffes.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.fyffes.com\/es\/#\/schema\/person\/1f808945ce4f6506661c84191713175b","name":"sampower","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/436be0e66150be7058de9d0442e56ca570b7d2fced5b180e61e3b72387b4735b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/436be0e66150be7058de9d0442e56ca570b7d2fced5b180e61e3b72387b4735b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/436be0e66150be7058de9d0442e56ca570b7d2fced5b180e61e3b72387b4735b?s=96&d=mm&r=g","caption":"sampower"},"url":"https:\/\/www.fyffes.com\/es\/news\/author\/sampower\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/posts\/4298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/comments?post=4298"}],"version-history":[{"count":4,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/posts\/4298\/revisions"}],"predecessor-version":[{"id":4306,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/posts\/4298\/revisions\/4306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/media\/4302"}],"wp:attachment":[{"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/media?parent=4298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/categories?post=4298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fyffes.com\/es\/wp-json\/wp\/v2\/tags?post=4298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}